{"id":3248,"count":1,"description":"","link":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/","name":"pemberdayaan masyarakat desa","slug":"pemberdayaan-masyarakat-desa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pemberdayaan masyarakat desa Archives - ppmindonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pemberdayaan masyarakat desa Archives - ppmindonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/\" \/>\n<meta property=\"og:site_name\" content=\"ppmindonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/index.php\\\/tag\\\/pemberdayaan-masyarakat-desa\\\/\",\"url\":\"https:\\\/\\\/ppmindonesia.com\\\/index.php\\\/tag\\\/pemberdayaan-masyarakat-desa\\\/\",\"name\":\"pemberdayaan masyarakat desa Archives - ppmindonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/index.php\\\/tag\\\/pemberdayaan-masyarakat-desa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/index.php\\\/tag\\\/pemberdayaan-masyarakat-desa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ppmindonesia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pemberdayaan masyarakat desa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#website\",\"url\":\"https:\\\/\\\/ppmindonesia.com\\\/\",\"name\":\"ppm\",\"description\":\"The Center for People Participation\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppmindonesia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#organization\",\"name\":\"ppm\",\"url\":\"https:\\\/\\\/ppmindonesia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppmindonesia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-Hiring___2_-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/ppmindonesia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-Hiring___2_-removebg-preview.png\",\"width\":572,\"height\":141,\"caption\":\"ppm\"},\"image\":{\"@id\":\"https:\\\/\\\/ppmindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pemberdayaan masyarakat desa Archives - ppmindonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/","og_locale":"en_US","og_type":"article","og_title":"pemberdayaan masyarakat desa Archives - ppmindonesia","og_url":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/","og_site_name":"ppmindonesia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/","url":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/","name":"pemberdayaan masyarakat desa Archives - ppmindonesia","isPartOf":{"@id":"https:\/\/ppmindonesia.com\/#website"},"breadcrumb":{"@id":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ppmindonesia.com\/index.php\/tag\/pemberdayaan-masyarakat-desa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ppmindonesia.com\/"},{"@type":"ListItem","position":2,"name":"pemberdayaan masyarakat desa"}]},{"@type":"WebSite","@id":"https:\/\/ppmindonesia.com\/#website","url":"https:\/\/ppmindonesia.com\/","name":"ppm","description":"The Center for People Participation","publisher":{"@id":"https:\/\/ppmindonesia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppmindonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ppmindonesia.com\/#organization","name":"ppm","url":"https:\/\/ppmindonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ppmindonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/ppmindonesia.com\/wp-content\/uploads\/2024\/05\/cropped-Hiring___2_-removebg-preview.png","contentUrl":"https:\/\/ppmindonesia.com\/wp-content\/uploads\/2024\/05\/cropped-Hiring___2_-removebg-preview.png","width":572,"height":141,"caption":"ppm"},"image":{"@id":"https:\/\/ppmindonesia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ppmindonesia.com\/index.php\/wp-json\/wp\/v2\/tags\/3248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppmindonesia.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ppmindonesia.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ppmindonesia.com\/index.php\/wp-json\/wp\/v2\/posts?tags=3248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}